{"id":49,"date":"2015-03-08T17:02:45","date_gmt":"2015-03-08T17:02:45","guid":{"rendered":"http:\/\/portaileduc.net\/website\/?p=49"},"modified":"2015-03-08T17:02:45","modified_gmt":"2015-03-08T17:02:45","slug":"liste-des-reseaux-denseignants","status":"publish","type":"post","link":"https:\/\/portaileduc.net\/website\/liste-des-reseaux-denseignants\/","title":{"rendered":"Liste des r\u00e9seaux d\u2019enseignants"},"content":{"rendered":"<p>Sur son site, Isabelle Quentin recense des structures associatives produisant \u00e0 la fois de <strong>l\u2019information<\/strong> (espaces de communication descendantes et \/ ou espaces d\u2019\u00e9changes entre pairs) et des <strong>ressources professionnelles<\/strong> (banques de ressources p\u00e9dagogiques et \/ ou conception d\u2019outils ou de logiciels pour enseigner<em>).\u00a0<\/em><\/p>\n<p><a href=\"https:\/\/isabellequentin.wordpress.com\/liste-des-reseaux-denseignants\/\" target=\"_blank\">En voici la liste, que vous retrouvez aussi sur son site :<\/a><\/p>\n<p><a href=\"https:\/\/isabellequentin.wordpress.com\/liste-des-reseaux-denseignants\/\" target=\"_blank\">https:\/\/isabellequentin.wordpress.com\/liste-des-reseaux-denseignants\/<\/a><\/p>\n<p>&nbsp;<\/p>\n<h3>Les r\u00e9seaux de pairs et les associations disciplinaires pour tous les niveaux d\u2019enseignements<\/h3>\n<ul>\n<li style=\"text-align: justify;\"><span style=\"text-decoration: underline;\"><a href=\"http:\/\/www.aideauxprofs.org\/index.asp?affiche=Accueil.asp\" target=\"_blank\"><strong>Aide aux profs<\/strong><\/a> :<\/span> Aide aux Profs a pour objectifs la d\u00e9fense et la promotion des secondes carri\u00e8res pour les professeurs de tous niveaux, de tous statuts, du public et du priv\u00e9, r\u00e9sidant en France et dans tout pays francophone.<\/li>\n<li style=\"text-align: justify;\"><strong><a href=\"http:\/\/aggiornamento.hypotheses.org\/%20.\" target=\"_blank\">Aggiornamento Histoire-G\u00e9ographie <\/a><\/strong>est un r\u00e9seau informel \u00e9laborant des r\u00e9flexions et propositions pour un renouvellement de l\u2019enseignement de l\u2019histoire et de la g\u00e9ographie du primaire \u00e0 l\u2019universit\u00e9.<\/li>\n<li style=\"text-align: justify;\"><strong><span style=\"text-decoration: underline;\"><a href=\"http:\/\/www.apprendre2point0.org\/\" target=\"_blank\">Apprendre 2.0<\/a> <\/span><\/strong>: Apprendre 2.0 est un r\u00e9seau rassemblant plus de 2000 membres dont l\u2019objectif est de d\u00e9battre des impacts des nouvelles technologies sur les fa\u00e7ons \u00a0d\u2019apprendre.<\/li>\n<li style=\"text-align: justify;\"><strong><span style=\"text-decoration: underline;\"><a href=\"http:\/\/edupln.ning.com\/\" target=\"_blank\">Educators PLN<\/a><\/span><\/strong> : Educators PNL est un r\u00e9seau social pour discuter du \u201cPersonal Learning Network\u201d en contexte \u00e9ducatif.<\/li>\n<li style=\"text-align: justify;\"><strong><span style=\"text-decoration: underline;\"><a href=\"http:\/\/enseignement-lsf.com\/spip.php?article272\" target=\"_blank\">E-LSF<\/a><\/span><\/strong> :E-LSF un site fait par des enseignants pour des enseignants. Il s\u2019adresse aux enseignants de et en LSF (Langue des Signes Fran\u00e7aise). Il permet de partager des ressources p\u00e9dagogiques et des outils destin\u00e9s \u00e0 l\u2019enseignement de la LSF.<\/li>\n<li style=\"text-align: justify;\"><span style=\"text-decoration: underline;\"><a href=\"http:\/\/www.elab.fr\/site\/\" target=\"_blank\"><strong>El@b<\/strong> <\/a>: <\/span>El@b est un espace d\u2019\u00e9changes sur les pratiques p\u00e9dagogiques. Il a pour objectif de donner aux enseignants une vision globale et commune de l\u2019\u00c9cole et de les aider \u00e0 exp\u00e9rimenter pour innover.<\/li>\n<li style=\"text-align: justify;\"><a href=\"http:\/\/www.enseignons.be\/\" target=\"_blank\"><strong>Enseignons.be<\/strong><\/a> : Enseignons.be a pour objectif de permettre aux enseignants d\u2019\u00e9changer des ressources p\u00e9dagogiques class\u00e9es par disciplines et par niveaux d\u2019enseignement.<\/li>\n<li style=\"text-align: justify;\"><a href=\"http:\/\/www.instruire.fr\" target=\"_blank\"><strong>GRIP <\/strong><\/a><strong>: <\/strong>Groupement Interdisciplinaire de R\u00e9flexion sur les Programmes, r\u00e9unissant instituteurs, professeurs du secondaire et de pr\u00e9pa.<\/li>\n<li><strong><a href=\"http:\/\/www.icem-freinet.org\/baseNet1\/frntPorte.htm\" target=\"_blank\">La liste Freinet<\/a><\/strong> : pour toutes les personnes s\u2019int\u00e9ressant \u00e0 la p\u00e9dagogie Freinet.<\/li>\n<li style=\"text-align: justify;\"><a href=\"www.printemps-education.org\" target=\"_blank\"><strong>Le Printemps de l\u2019\u00c9ducation<\/strong><\/a> : Ce r\u00e9seau cherche \u00e0 partager les connaissances et savoir-faire en mati\u00e8re d\u2019\u00e9ducation et de p\u00e9dagogie avec les enseignants, les parents et les \u00e9tudiants.<\/li>\n<li style=\"text-align: justify;\"><strong><a href=\"http:\/\/www.reseau-des-professeursparticuliers.fr\/\" target=\"_blank\">Le r\u00e9seau des professeurs ind\u00e9pendants <\/a><\/strong>: Ce r\u00e9seau cherche valoriser le statut et la fiche de paie du professeur ind\u00e9pendant en l\u2019accompagnant dans le d\u00e9veloppement de son activit\u00e9.<\/li>\n<li style=\"text-align: justify;\">mon <strong><a href=\"http:\/\/moncahierjournal.com\/\">CahierJournal.com<\/a><\/strong> est un logiciel en ligne d\u00e9di\u00e9 \u00e0 la gestion du cahier journal des enseignants du primaire et du secondaire.<\/li>\n<li style=\"text-align: justify;\"><strong><span style=\"text-decoration: underline;\"><a href=\"http:\/\/www.neoprofs.org\/\" target=\"_blank\">Neoprofs<\/a><\/span><\/strong> : Neoprofs est un lieu d\u2019\u00e9changes et de discussion entre enseignants.<\/li>\n<li style=\"text-align: justify;\"><a href=\"http:\/\/www.planete-enseignant.com\/\" target=\"_blank\"><strong><span style=\"text-decoration: underline;\">Plan\u00e8te Enseignant <\/span><\/strong><\/a>: Plan\u00e8te Enseignant est un site interactif dont l\u2019objectif est de contribuer \u00e0 am\u00e9liorer la fonction et la vie des enseignants.<\/li>\n<li style=\"text-align: justify;\"><a href=\"http:\/\/projetice.fr\/\" target=\"_blank\"><strong>PROJETICE<\/strong><\/a> : PROJETICE est une association qui aide les enseignants \u00e0 d\u00e9velopper des projets Tice.<\/li>\n<li style=\"text-align: justify;\"><strong><a href=\"http:\/\/www.scolaprof.fr\" target=\"_blank\" rel=\"nofollow\">Scolaprof<\/a><\/strong> : Ce site a pour objectif de permettre aux enseignants qui le souhaitent, d\u2019\u00eatre \u00ab\u00a0ind\u00e9pendants\u00a0\u00bb pour transmettre leur savoir et aux parents\/\u00e9l\u00e8ves de b\u00e9n\u00e9ficier de soutien scolaire.<\/li>\n<li style=\"text-align: justify;\"><strong><a href=\"http:\/\/www.syn-lab.fr\/\" target=\"_blank\">Syn-lab <\/a><\/strong>: Cette association regroupe des acteurs souhaitant favoriser la co-cr\u00e9ation d\u2019innovations et leur g\u00e9n\u00e9ralisation dans l\u2019optique d\u2019un changement syst\u00e9mique dans l\u2019\u00e9ducation.<\/li>\n<li style=\"text-align: justify;\"><a href=\"http:\/\/www.radio-ecole.fr\/\" target=\"_blank\"><strong>Radio-\u00e9cole<\/strong> <\/a>: L\u2019association a pour objet d\u2019\u0153uvrer \u00e0 la mise en place de radio en milieu scolaire.<\/li>\n<li style=\"text-align: justify;\"><strong><a href=\"http:\/\/wimsedu.info\/\" target=\"_blank\">WIMS<\/a> EDU<\/strong> : Cette association a pour objectif de d\u00e9velopper les usages du logiciel libre WIMS (Web Interactive Multipurpose Server) en contexte \u00e9ducatif.<\/li>\n<li style=\"text-align: justify;\"><strong><a href=\"http:\/\/www.zerodeconduite.net\/\">Z\u00e9ro de Conduite<\/a><\/strong> : Z\u00e9ro de conduite est un blog sur le cin\u00e9ma r\u00e9alis\u00e9 par des enseignants \u00e0 destination des enseignants et des documentalistes, des parents et des \u00e9l\u00e8ves. Il a pour vocation de d\u00e9fendre et de promouvoir l\u2019utilisation du cin\u00e9ma comme outil p\u00e9dagogique.<\/li>\n<li style=\"text-align: justify;\">etc.<\/li>\n<\/ul>\n<h3 style=\"text-align: justify;\"><strong><strong>Les r\u00e9seaux de pairs et les associations pour l\u2019enseignement primaire<\/p>\n<p><\/strong><\/strong><\/h3>\n<ul style=\"text-align: justify;\">\n<li style=\"text-align: justify;\"><a href=\"http:\/\/www.ageem.fr\/\" target=\"_blank\"><strong>AGEEM<\/strong><\/a>: Elle a pour buts d\u2019\u00e9tudier toutes questions d\u2019ordre p\u00e9dagogique en vue du progr\u00e8s et du perfectionnement de l\u2019\u00e9ducation dans les \u00e9coles maternelles publiques, en dehors de toute tendance d\u2019ordre politique ou confessionnel.<\/li>\n<li style=\"text-align: justify;\"><strong><a href=\"http:\/\/www.fnaren.com\/\">FNAREM <\/a><\/strong>: La FNAREN a pour objectifs la recherche, la formation, l\u2019innovation et l\u2019information relatives aux pratiques et techniques professionnelles des r\u00e9\u00e9ducateurs.<\/li>\n<li style=\"text-align: justify;\"><strong><a href=\"http:\/\/www.fname.fr\/\">FNAME<\/a><\/strong> : Elle a pour buts de promouvoir l\u2019information, la recherche, la formation et l\u2019innovation p\u00e9dagogique, de favoriser la reconnaissance de la sp\u00e9cificit\u00e9 du travail et de l\u2019identit\u00e9 professionnelle des enseignants sp\u00e9cialis\u00e9s, option E et assimil\u00e9s, travaillant sur des postes sp\u00e9cialis\u00e9s dans le cadre de l\u2019\u00e9cole publique, d\u2019\u0153uvrer \u00e0 la cr\u00e9ation d\u2019associations d\u00e9partementales ou r\u00e9gionales des Ma\u00eetres E, \u00e0 la cr\u00e9ation d\u2019une structure nationale des Associations du secteur de l\u2019Adaptation et de la Scolarisation des \u00e9l\u00e8ves en situation de Handicap<\/li>\n<li style=\"text-align: justify;\"><strong><a href=\"http:\/\/forums-enseignants-du-primaire.com\/\" target=\"_blank\">Enseignants du primaire <\/a><\/strong>: Un forum de discussions pour les enseignants du primaire.<\/li>\n<li style=\"text-align: justify;\"><strong><a href=\"http:\/\/educasciences.ning.com\/\" target=\"_blank\">Enseigner les sciences <\/a><\/strong>: Enseigner les sciences est un espace num\u00e9rique d\u2019\u00e9change et de formation concernant l\u2019enseignement des sciences \u00e0 l\u2019\u00e9cole primaire.<\/li>\n<li style=\"text-align: justify;\"><a href=\"http:\/\/www.fondation-lamap.org\" target=\"_blank\"><strong>La main \u00e0 la p\u00e2te<\/strong> <\/a>: La main \u00e0 la p\u00e2te a pour le but de r\u00e9nover l\u2019enseignement des sciences et de la technologie \u00e0 l\u2019\u00e9cole primaire en favorisant un enseignement fond\u00e9 sur une d\u00e9marche d\u2019investigation scientifique. Son site vient d\u2019\u00eatre r\u00e9nov\u00e9 et propose davantage de contenus scientifiques et p\u00e9dagogiques ainsi que d\u2019espaces communautaires.<\/li>\n<li><strong><a href=\"http:\/\/www.pmev.fr\/\">PMEV<\/a><\/strong> : La PMEV propose une organisation sp\u00e9cifique de la classe r\u00e9pondant \u00e0 quelques principes pr\u00e9cis, avec un objectif tr\u00e8s simple : gagner en efficacit\u00e9 et en confort de travail.<\/li>\n<li style=\"text-align: justify;\">etc.<\/li>\n<\/ul>\n<h3 style=\"text-align: justify;\"><strong>Les r\u00e9seaux de pairs et les associations disciplinaires du secondaire<\/p>\n<p><\/strong><\/h3>\n<ul style=\"text-align: justify;\">\n<li><a href=\"http:\/\/www.aecme.fr\/\"><strong>AECME<\/strong>:<\/a> l\u2019Association des Enseignants de la Composition en Musique \u00c9lectroacoustique (AECME) a pour ambition de regrouper les enseignants de cet art, de promouvoir celui-ci et d\u2019organiser des \u00e9changes entre les enseignants de cette discipline.<\/li>\n<li><a href=\"http:\/\/www.site.aeeps.org\/\" target=\"_blank\"><strong>AE-EPS<\/strong> <\/a>: Il s\u2019agit d\u2019une association de sp\u00e9cialistes de l\u2019enseignement de l\u2019\u00e9ducation physique et sportive, ouverte \u00e0 toute personne charg\u00e9e de l\u2019enseignement de cette discipline ou qui se destine \u00e0 cet enseignement.<\/li>\n<li><a href=\"http:\/\/afdet.org\/2009\/index.php3?fichier_gauche=2005_menu_1_template6&amp;session=b42868364be25249db6107480570c7661020&amp;id_internet_news=24&amp;id_image_news=23&amp;langue=0&amp;categorie=0&amp;liste=0\" target=\"_blank\"><strong>AFDET<\/strong> <\/a>: L\u2019AFDET cherche \u00e0 valoriser l\u2019enseignement technique, de sorte que chaque jeune qui s\u2019y oriente, ait la garantie d\u2019une formation et d\u2019une insertion professionnelle r\u00e9ussie.<\/li>\n<li><a href=\"http:\/\/www.afef.org\/blog\/#\" target=\"_blank\"><strong>AFEF<\/strong> <\/a>: Son but est de contribuer \u00e0 enseigner le fran\u00e7ais dans la diversit\u00e9 des usages de la langue et des pratiques sociales et culturelles, la continuit\u00e9 tout au long de la scolarit\u00e9, sans cloisonnement par cycles pour tous les \u00e9l\u00e8ves, sans condition d\u2019origine sociale, linguistique, ethnique.<\/li>\n<li><a href=\"http:\/\/afpc.asso.fr\/\" target=\"_blank\"><strong>AFPC<\/strong> <\/a>: L\u2019AFPC est l\u2019association repr\u00e9sentative de l\u2019enseignement du chinois et a pour objet la promotion de l\u2019enseignement de la langue et de la culture chinoises.<\/li>\n<li><strong><a href=\"http:\/\/www.andep.org\/\" target=\"_blank\">ANDEP<\/a> : <\/strong>association nationale des professeurs documentalistes de l\u2019enseignement priv\u00e9.<\/li>\n<li><a href=\"http:\/\/www.anpbse.com\/index.php?\" target=\"_blank\"><strong>ANPBSE<\/strong> <\/a>: L\u2019ANPBSE a pour but de d\u00e9fendre et promouvoir les enseignements de Biotechnologies option Sant\u00e9 Environnement et constituer un lien permanent entre les professeurs de biotechnologie.<\/li>\n<li><strong><a href=\"http:\/\/apagsite.com\/\">APAG<\/a>\u00a0:<\/strong> association des professeurs d\u2019anglais de la Guadeloupe<\/li>\n<li><strong><a href=\"http:\/\/www.apbg.org\/\" target=\"_blank\">APBG<\/a><\/strong> :l\u2019association des professeurs de biologie g\u00e9ologie\u00a0regroupe les professeurs enseignant la biologie-g\u00e9ologie (sciences naturelles) de tous les ordres d\u2019enseignement : \u00e9cole, coll\u00e8ge, lyc\u00e9e (professeurs de biologie-g\u00e9ologie) et enseignement sup\u00e9rieur, d\u00e9sirant mettre en commun leurs exp\u00e9riences p\u00e9dagogiques et leur documentation.<\/li>\n<li><a href=\"http:\/\/www.apeg.info\/\" target=\"_blank\"><strong>APCEG<\/strong><\/a> : L\u2019APCEG a pour objectif la d\u00e9fense et la promotion des enseignements d\u2019\u00c9conomie-Gestion.<\/li>\n<li><a href=\"http:\/\/www.apdcg.net\/\" target=\"_blank\"><strong>APDCG<\/strong><\/a> : L\u2019APDCG a pour objectif d\u2019informer sur les questions relatives \u00e0 l\u2019enseignement dans les classes pr\u00e9paratoires \u00e0 l\u2019expertise comptable de l\u2019enseignement public, de favoriser les \u00e9changes entre enseignants ainsi qu\u2019avec les acteurs du monde \u00e9ducatif et \u00e9conomique.<\/li>\n<li><a href=\"http:\/\/www.apemu.fr\/presentation-apemu\"><strong>APEMU<\/strong><\/a> : L\u2019APEMU regroupe les professeurs d\u2019\u00e9ducation musicale.<\/li>\n<li><strong><a href=\"http:\/\/www.aphg.fr\/\" target=\"_blank\">APHG <\/a><\/strong>: Elle a \u00e9t\u00e9 fond\u00e9e pour \u00e9tudier les questions relatives \u00e0 l\u2019enseignement de l\u2019histoire et de la g\u00e9ographie, grouper tous les renseignements utiles pour la bonne organisation mat\u00e9rielle de cet enseignement, d\u00e9fendre la libert\u00e9 p\u00e9dagogique et morale de ses membres.<\/li>\n<li><strong><a href=\"http:\/\/www.aplv-languesmodernes.org\/\" target=\"_blank\">APLV<\/a><\/strong> :Elle regroupe des enseignants de toutes les langues.<\/li>\n<li><strong><a href=\"http:\/\/www.apmep.asso.fr\/\" target=\"_blank\">APMEP<\/a><\/strong> : Cette association a pour objectif de s\u2019engager ou soutenir toute action qui lui para\u00eet propre \u00e0 am\u00e9liorer l\u2019enseignement des math\u00e9matiques.<\/li>\n<li><strong><a href=\"http:\/\/www.appep.net\/\" target=\"_blank\">APPEP <\/a><\/strong>: L\u2019 Association des Professeurs de Philosophie de l\u2019Enseignement Public s\u2019adresse \u00e0 tous les coll\u00e8gues de philosophie pour mieux faire conna\u00eetre ses positions et ses revendications.<\/li>\n<li><strong><a href=\"..\/les-associations-disciplinaires-denseignants\/www.apses.org\/\" target=\"_blank\">APSES<\/a><\/strong> : L\u2019APSES se d\u00e9crit comme un engagement militant qui correspond en effet au projet de l\u2019enseignement des sciences \u00e9conomiques et sociales : donner les moyens aux \u00e9l\u00e8ves de comprendre les enjeux \u00e9conomiques, politiques et sociaux et la complexit\u00e9 du monde.<\/li>\n<li><strong><a href=\"http:\/\/www.ac-grenoble.fr\/apisp\/index.htm\" target=\"_blank\">APISP <\/a>:<\/strong> Association des Professeurs d\u2019Initiation aux Sciences Physiques<\/li>\n<li><strong><a href=\"http:\/\/www.biotechno.fr\/\" target=\"_blank\">Biotechno<\/a><\/strong> : Ce site est con\u00e7u par et pour les enseignants de Biotechnologies Sant\u00e9-Environnement (PLP). Il pr\u00e9sente des productions p\u00e9dagogiques.<\/li>\n<li style=\"text-align: justify;\"><strong><a href=\"http:\/\/www.chlorofil.fr\/ressources-et-pratiques-educatives\/tice-et-foad-technologies-de-linformation-et-de-la-communication-pour-lenseignement-et-formations-ouvertes-et-a-distance.html\" target=\"_blank\">ChloroFil<\/a><\/strong> :ChloroFil est un espace Web d\u00e9di\u00e9 aux professionnels de l\u2019enseignement agricole fran\u00e7ais.<\/li>\n<li style=\"text-align: justify;\"><a href=\"http:\/\/www.cnarela.fr\/\" target=\"_blank\"><strong>CNARELLA<\/strong><\/a> : L\u2019objectif principal de l\u2019association CNARELLA est de favoriser l\u2019enseignement du latin et du grec dans les \u00e9tablissements secondaires et sup\u00e9rieurs, non seulement comme sp\u00e9cialit\u00e9, mais encore comme \u00e9l\u00e9ment d\u2019une formation et d\u2019une culture g\u00e9n\u00e9rales. Elle se propose \u00e9galement de susciter l\u2019int\u00e9r\u00eat du plus large public pour l\u2019antiquit\u00e9.<\/li>\n<li style=\"text-align: justify;\"><strong><a href=\"http:\/\/www.cyber-langues.asso.fr\/\" target=\"_blank\">Cyberlangues<\/a> <\/strong>: Cyberlangues a pour but de rapprocher les professeurs de langues utilisant les TIC et de leur permettre d\u2019\u00e9changer des pratiques innovantes.<\/li>\n<li style=\"text-align: justify;\"><strong><a href=\"http:\/\/docsdocs.free.fr\/\" target=\"_blank\">Docspourdocs <\/a><\/strong>: L\u2019objectif du r\u00e9seau Docspourdocs est de mutualiser des ressources p\u00e9dagogiques pour les professeurs documentalistes.<\/li>\n<li style=\"text-align: justify;\"><strong><a href=\"http:\/\/www.fadben.asso.fr\/\" target=\"_blank\">FADBEN<\/a><\/strong> : Son but est de pro\u00adposer et d\u2019organiser une r\u00e9flexion pros\u00adpective concernant l\u2019exercice du m\u00e9tier d\u2019enseignant docu\u00admen\u00adta\u00adliste, la for\u00admation ini\u00adtiale et continue de ces ensei\u00adgnants, la recherche p\u00e9da\u00adgo\u00adgique et uni\u00adver\u00adsi\u00adtaire qui y\u00a0sont rat\u00adta\u00adch\u00e9es.<\/li>\n<li style=\"text-align: justify;\"><strong><a href=\"http:\/\/www.clionautes.org\/\" target=\"_blank\">Les Clionautes<\/a><\/strong> : Cette association cherche \u00e0 promouvoir l\u2019utilisation des technologies num\u00e9riques en histoire, g\u00e9ographie et en \u00e9ducation civique. Ses membres d\u00e9fendent les d\u00e9marches de p\u00e9dagogie active et souhaitent favoriser la mutualisation entre enseignants et les projets d\u2019\u00e9tudiants et d\u2019\u00e9l\u00e8ves.<\/li>\n<li style=\"text-align: justify;\"><strong><a href=\"http:\/\/physiquechimie.forum.free.fr\/\" target=\"_blank\">Le forum des professeurs de Physique Chimie\u00a0<\/a><\/strong> : Sa devise est partager pour mieux enseigner la physique et la chimie.<\/li>\n<li style=\"text-align: justify;\"><strong><a href=\"http:\/\/www.lemanege.eu\/\" target=\"_blank\">Lemanege <\/a><\/strong>: Lemanege est un site de mutualisation de ressources p\u00e9dagogiques en \u00e9conomie-gestion.<\/li>\n<li style=\"text-align: justify;\"><strong><a href=\"http:\/\/www.pagestec.org\/web2001\/index.php?op=edito\" target=\"_blank\">Pagestec <\/a><\/strong>: Pagestec a pour but de regrouper des acteurs de l\u2019enseignement de la technologie afin de mettre en commun des moyens mat\u00e9riels et leur exp\u00e9rience professionnelle. Son objectif est de favoriser et f\u00e9d\u00e9rer l\u2019Internet collaboratif comme un outil de d\u00e9veloppement de la technologie en coll\u00e8ge et d\u00e9fendre les conditions d\u2019enseignement de la technologie, afin de mieux pr\u00e9parer les \u00e9l\u00e8ves \u00e0 leur avenir.<\/li>\n<li style=\"text-align: justify;\"><strong><a href=\"http:\/\/www.philocegep.com\/\" target=\"_blank\">PhiloC\u00e9gep <\/a><\/strong>: PhiloC\u00e9gep se d\u00e9finit comme le r\u00e9seau social des profs de philo des c\u00e9geps.<\/li>\n<li style=\"text-align: justify;\"><strong><a href=\"http:\/\/www.sesamath.net\/\" target=\"_blank\">S\u00e9samath<\/a><\/strong> : L\u2019association S\u00e9samath a pour vocation essentielle de mettre \u00e0 disposition de tous, gratuitement, des ressources p\u00e9dagogiques libres et des outils professionnels libres utilis\u00e9s pour l\u2019enseignement des math\u00e9matiques via Internet.<\/li>\n<li style=\"text-align: justify;\"><a href=\"http:\/\/www.cfe.free.fr\/\" target=\"_blank\"><strong>STGCFE<\/strong><\/a> : STGCFE est un site de mutualisation de ressources p\u00e9dagogiques en \u00e9conomie gestion.<\/li>\n<li style=\"text-align: justify;\"><strong><a href=\"http:\/\/www.sti2d.fr\/\">STI2D<\/a><\/strong> : Le but de STI2D Le but est de fournir un support ind\u00e9pendant aux enseignants qui enseignent le bac STI2D pour le partage d\u2019id\u00e9es ou de TP.<\/li>\n<li style=\"text-align: justify;\"><a href=\"http:\/\/44.svt.free.fr\/\" target=\"_blank\"><strong>SVT \u2013 44<\/strong><\/a> : SVT \u2013 44 est un site de mutualisation et de partage de ressources en sciences de la vie et de la terre \u00e0 l\u2019origine pour l\u2019enseignement secondaire et d\u00e9sormais \u00e9galement pour l\u2019enseignement primaire<\/li>\n<li style=\"text-align: justify;\"><strong><a href=\"http:\/\/fsincere.free.fr\/sti2d\/ressources_sti2d.php\">\u03c62D : <\/a><\/strong><big>Ce site s\u2019adresse aux enseignants de Sciences Physiques en Premi\u00e8re et Terminale STI2D-STL<\/big>. <big>Son but est de mettre \u00e0 disposition des ressources p\u00e9dagogiques : cours, exercices, devoirs, qcm, travaux pratiques, vid\u00e9os, logiciels\u2026<\/big><\/li>\n<li style=\"text-align: justify;\"><a href=\"http:\/\/www.udppc.asso.fr\/national\/\" target=\"_blank\"><strong>UDPPC<\/strong> :<\/a> union des professeurs de physique chimie<\/li>\n<li style=\"text-align: justify;\"><strong><a href=\"http:\/\/www.upbm.org\/\" target=\"_blank\">UPBM<\/a><\/strong> rassemble les professeurs de biotechnologies enseignant dans les sections technologiques STL (Sciences et techniques de laboratoire, option biotechnologies) et dans les sections biologiques des BTS et IUT (pr\u00e9parant les dipl\u00f4mes de techniciens sup\u00e9rieurs en biologie notamment m\u00e9dicale). L\u2019association \u00e9dite une revue, l\u2019Op\u00e9ron, des annales des sujets, des planches, et un ouvrage sur le pr\u00e9l\u00e8vement sanguin.<\/li>\n<li style=\"text-align: justify;\"><strong><a href=\"http:\/\/www.upsti.fr\/spip.php?rubrique3\" target=\"_blank\">UPSTI <\/a><\/strong>:\u00a0 L\u2019Union des Professeurs de Sciences et Techniques Industrielles. Cr\u00e9\u00e9e en 1982, elle f\u00e9d\u00e8re et cr\u00e9e un r\u00e9seau de plus de 700 Professeurs de Sciences de l\u2019Ing\u00e9nieur, r\u00e9partis dans plus de 200 lyc\u00e9es publics ou priv\u00e9s sous contrat, exer\u00e7ant dans les Classes Pr\u00e9paratoires aux Grandes Ecoles (CPGE) scientifiques.<\/li>\n<li style=\"text-align: justify;\"><strong><a href=\"http:\/\/www.weblettres.net\/index.php\" target=\"_blank\">WebLettres<\/a> : <\/strong>WebLettres est le site associatif des professeurs de fran\u00e7ais. Anim\u00e9 par une trentaine d\u2019enseignants b\u00e9n\u00e9voles, il a pour vocation de favoriser les \u00e9changes, et propose notamment des listes de discussion et un espace partag\u00e9 pour la mise en ligne de cours et s\u00e9quences didactiques<strong>.<\/strong><\/li>\n<li style=\"text-align: justify;\">etc.<\/li>\n<\/ul>\n<h2><strong>Les journaux et les revues en ligne<\/p>\n<p><\/strong><\/h2>\n<ul>\n<li style=\"text-align: justify;\"><a href=\"http:\/\/www.acteurs-ecoles.fr\/\" target=\"_blank\"><strong>An@\u00e9 <\/strong><\/a>: An@\u00e9 mutualise les ressources et les activit\u00e9s de l\u2019association Educavox sp\u00e9cialis\u00e9e dans les d\u00e9bats sur l\u2019\u00e9ducation, la valorisation des usages notamment avec les Tice.<\/li>\n<li style=\"text-align: justify;\"><strong><a href=\"http:\/\/www.cahiers-pedagogiques.com\/\">Les Cahiers P\u00e9dagogiques<\/a><\/strong> : Cette revue cherche \u00e0 allier la r\u00e9flexion des enseignants de terrain sur leurs pratiques et les contributions des chercheurs.<\/li>\n<li style=\"text-align: justify;\"><strong><a href=\"http:\/\/www.cafepedagogique.net\/\">Le Caf\u00e9 p\u00e9dagogique<\/a><\/strong> : R\u00e9alis\u00e9 par un collectif d\u2019enseignants et de chercheurs en sciences de l\u2019\u00e9ducation, le Caf\u00e9 p\u00e9dagogique est une revue p\u00e9dagogique \u00e9lectronique.<\/li>\n<li style=\"text-align: justify;\"><strong><a href=\"http:\/\/www.cnt-f.org\/nautreecole\/\" target=\"_blank\">N\u2019autre \u00e9col<\/a>e<\/strong> : Revue de la f\u00e9d\u00e9ration CNT des travailleurs de l\u2019\u00e9ducation<\/li>\n<li style=\"text-align: justify;\"><a href=\"http:\/\/www.questionsdeclasses.org\/\" target=\"_blank\"><strong>Questions de classe(s)<\/strong> :<\/a> site d\u2019information et d\u2019\u00e9changes sur les p\u00e9dagogies alternatives et les luttes sociales dans l\u2019\u00e9ducation.<\/li>\n<\/ul>\n<h2><strong>Les plateformes et les outils d\u00e9di\u00e9s \u00e0 l\u2019\u00e9ducation<\/p>\n<p><\/strong><\/h2>\n<ul>\n<li style=\"text-align: justify;\"><a href=\"http:\/\/abuledu-fr.org\/\" target=\"_blank\">Abul\u00c9du-fr<\/a> qui a pour but a pour but de promouvoir, d\u2019organiser, de diffuser des solutions logicielles et mat\u00e9rielles \u00e0 destination des utilisateurs de la solution Abul\u00c9du<\/li>\n<li style=\"text-align: justify;\"><strong><a href=\"http:\/\/ingefor.aptilink.com\" target=\"_blank\">Apilink<\/a><\/strong>*\u00a0 articles d\u2019experts et de membres, points de vue, sondage et discussions\u2026<\/li>\n<li style=\"text-align: justify;\"><a href=\"https:\/\/babytwit.fr\" target=\"_blank\"><strong>Babytwit<\/strong> :<\/a>\u00a0site de micro-blogue d\u00e9di\u00e9 aux \u00e9coles primaires.<\/li>\n<li style=\"text-align: justify;\"><strong><a href=\"http:\/\/www.beebac.com\/\" target=\"_blank\">Beebac<\/a><\/strong> : Beebac se d\u00e9finit comme une communaut\u00e9 regroupant coll\u00e9giens, lyc\u00e9ens, \u00e9tudiants, enseignants, professeurs et professionnels utilisant les fonctionnalit\u00e9s du Web 2.0 pour apprendre et enseigner diff\u00e9remment.<\/li>\n<li style=\"text-align: justify;\"><strong><a href=\"http:\/\/www.classroom20.com\/\" target=\"_blank\">Classroom 2.0<\/a> <\/strong>: Classroom 2.0 se d\u00e9finit comme un r\u00e9seau social pour ceux qui s\u2019int\u00e9ressent aux technologies participatives en \u00e9ducation.<\/li>\n<li style=\"text-align: justify;\"><strong><a href=\"http:\/\/wiki.educoo.org\/index.php\/Main_Page\/fr\" target=\"_blank\">EducOOo<\/a> <\/strong>: EducOOo a pour objectif de faciliter la mise en place et l\u2019accompagnement de projets entre OpenOffice.org et le monde de l\u2019Enseignement. EducOOo assure le d\u00e9veloppement des suites bureautiques libres all\u00e9g\u00e9es <a href=\"http:\/\/wiki.ooo4kids.org\/index.php\/Main_Page\/fr\">OOo4Kids<\/a> pour les 7- 12 ans et <a href=\"http:\/\/wiki.ooolight.org\/index.php\/Main_Page\/fr\">OOoLight<\/a> pour les seniors.<\/li>\n<li style=\"text-align: justify;\">Edmodo<\/li>\n<li style=\"text-align: justify;\"><strong><a href=\"http:\/\/maternet.over-blog.com\/\" target=\"_blank\">M@TERNET<\/a><\/strong> : M@TERNET est annuaire pour les enseignant(e)s en maternelle. Il propose \u00e9galement quelques ressources pour utiliser les Tic en maternelle.<\/li>\n<li style=\"text-align: justify;\"><strong><a href=\"http:\/\/mespreps.com\/\" target=\"_blank\">MesPreps<\/a><\/strong> : MesPreps est un site d\u2019aide \u00e0 la conception de fiches de pr\u00e9paration. Ces fiches sont ensuite partag\u00e9es gratuitement et librement entre les utilisateurs inscrits.<\/li>\n<li style=\"text-align: justify;\"><strong><a href=\"http:\/\/www.lyclic.fr\/\" target=\"_blank\">Lyclic<\/a> <\/strong>: Lyclic est une plateforme web d\u00e9di\u00e9e au lyc\u00e9e.<\/li>\n<li style=\"text-align: justify;\"><strong><a href=\"http:\/\/www.gensenegal.org\/palette\/2page3a.htm#Questceque\" target=\"_blank\">Palette<\/a> <\/strong>: Palette met \u00e0 la disposition des enseignants des outils p\u00e9dagogiques des albums, des recueils de textes et introduisant les fondements de la science et de la technologie. Elle vise\u00a0 \u00e0 pr\u00e9server le patrimoine culturel et traditionnel aux moyens des Tic.<\/li>\n<li style=\"text-align: justify;\"><strong><a href=\"http:\/\/peclic.com\/\" target=\"_blank\">PEclics<\/a> :<\/strong> PEclic est un moteur de recherche d\u00e9di\u00e9 aux Professeurs des \u00c9coles. Son ambition est de faciliter la vie des profs des \u00e9coles qui cherchent des informations, des documents de travail, des id\u00e9es de projets ou des exercices.<\/li>\n<li style=\"text-align: justify;\"><strong><a href=\"http:\/\/respire.eduscol.education.fr\/\" target=\"_blank\">Respire<\/a><\/strong> : R\u00e9seaux d\u2019\u00e9changes en innovation, recherche et en exp\u00e9rimentation entre les professionnels de l\u2019\u00e9ducation<\/li>\n<li style=\"text-align: justify;\"><strong><a href=\"http:\/\/exchange.smarttech.com\/#tab=0\" target=\"_blank\">Smart Exchange<\/a><\/strong> : Mutualisation de ressources \u00e0 utiliser avec le TBI Smart<\/li>\n<li style=\"text-align: justify;\"><strong><a href=\"http:\/\/www.tappedin.org\/\" target=\"_blank\">Tapped in<\/a><\/strong> : plateforme permettant de cr\u00e9er des communaut\u00e9s d\u2019enseignants<\/li>\n<li style=\"text-align: justify;\">Le <strong><a href=\"http:\/\/lewebpedagogique.com\/\" target=\"_blank\">Webp\u00e9dagogique<\/a><\/strong> : permet aux enseignants de cr\u00e9er un blog ou de partager des ressources sur des th\u00e9matiques li\u00e9es \u00e0 l\u2019\u00e9ducation, la formation ou les apprentissages.<\/li>\n<\/ul>\n<h2><strong>Les plateformes et les outils g\u00e9n\u00e9ralistes<\/strong><\/h2>\n<ul>\n<li style=\"text-align: justify;\"><a href=\"https:\/\/www.facebook.com\/\" target=\"_blank\"><strong>Facebook<\/strong> : <\/a>R\u00e9seau social permettant de cr\u00e9er des groupes<\/li>\n<li style=\"text-align: justify;\"><strong><a href=\"https:\/\/groups.google.com\/forum\/?fromgroups#!overview\" target=\"_blank\">Google Groupes : <\/a><\/strong>permet de cr\u00e9er des groupes de discussion<\/li>\n<li style=\"text-align: justify;\"><a href=\"http:\/\/www.ning.com\/\" target=\"_blank\"><strong>Ning* : <\/strong><\/a>plateforme permettant de cr\u00e9er des r\u00e9seaux et des communaut\u00e9s<\/li>\n<li style=\"text-align: justify;\"><a href=\"https:\/\/twitter.com\/\" target=\"_blank\"><strong>Twitter<\/strong> : <\/a>site de micro-blogging<\/li>\n<li>etc.<\/li>\n<\/ul>\n<p>* les outils et plateformes suivies d\u2019un * sont payants<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Sur son site, Isabelle Quentin recense des structures associatives produisant \u00e0 la fois de l\u2019information (espaces de communication descendantes et \/ ou espaces d\u2019\u00e9changes entre pairs) et des ressources professionnelles (banques de ressources p\u00e9dagogiques et \/ ou conception d\u2019outils ou de logiciels pour enseigner).\u00a0 En voici la liste, que vous retrouvez aussi sur son site [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[1],"tags":[18,21],"class_list":["post-49","post","type-post","status-publish","format-standard","category-informatique-numerique","tag-tic","tag-reseaux","czr-hentry"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p6aRPV-N","jetpack-related-posts":[{"id":44,"url":"https:\/\/portaileduc.net\/website\/reseaux-sociaux-et-education-groupes-facebook\/","url_meta":{"origin":49,"position":0},"title":"R\u00e9seaux sociaux et \u00e9ducation &#8211; Groupes Facebook","author":"Maxime Duquesnoy","date":"8 mars 2015","format":false,"excerpt":"30 groupes \u00e0 suivre sur Facebook source : http:\/\/blogues.csaffluents.qc.ca\/recit\/2014\/06\/18\/30-groupes-a-suivre-sur-facebook\/ \u00a0 G\u00c9N\u00c9RAL Enseignants et enseignantes du Qu\u00e9bec Groupe ferm\u00e9 de plus de 7660 membres \u00ab\u00a0pour tous les enseignants et enseignantes du Qu\u00e9bec. Un lieu de discussion et de partage au sujet de l\u2019enseignement et de l\u2019apprentissage.\u00a0\u00bb Enseignants suppl\u00e9ants du Qu\u00e9bec Groupe\u2026","rel":"","context":"Dans &quot;Informatique &amp; Num\u00e9rique&quot;","block_context":{"text":"Informatique &amp; Num\u00e9rique","link":"https:\/\/portaileduc.net\/website\/category\/domaines-disciplines\/informatique-numerique\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/portaileduc.net\/website\/wp-content\/uploads\/2015\/03\/facebook-notifications3-720x515.jpg?fit=720%2C515&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/portaileduc.net\/website\/wp-content\/uploads\/2015\/03\/facebook-notifications3-720x515.jpg?fit=720%2C515&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/portaileduc.net\/website\/wp-content\/uploads\/2015\/03\/facebook-notifications3-720x515.jpg?fit=720%2C515&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/portaileduc.net\/website\/wp-content\/uploads\/2015\/03\/facebook-notifications3-720x515.jpg?fit=720%2C515&ssl=1&resize=700%2C400 2x"},"classes":[]},{"id":2943,"url":"https:\/\/portaileduc.net\/website\/dans-la-toile-des-films-danimation-pour-connaitre-les-bonnes-pratiques-sur-internet\/","url_meta":{"origin":49,"position":1},"title":"Dans La Toile &#8211; Des films d&rsquo;animation pour conna\u00eetre les bonnes pratiques sur Internet","author":"Maxime Duquesnoy","date":"30 mars 2020","format":false,"excerpt":"Tv5 Monde propose des films d'animation pour conna\u00eetre les bonnes pratiques sur Internet tout en s'amusant. L'objectif ? Donner les cl\u00e9s aux jeunes ados (11-13 ans) pour utiliser les r\u00e9seaux sociaux au quotidien : r\u00e9fl\u00e9chir avant de publier, v\u00e9rifier les infos ou prot\u00e9ger ses donn\u00e9es. Liste des vid\u00e9os et des\u2026","rel":"","context":"Dans &quot;Informatique &amp; Num\u00e9rique&quot;","block_context":{"text":"Informatique &amp; Num\u00e9rique","link":"https:\/\/portaileduc.net\/website\/category\/domaines-disciplines\/informatique-numerique\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/portaileduc.net\/website\/wp-content\/uploads\/2020\/03\/danslatoile.png?fit=1167%2C485&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/portaileduc.net\/website\/wp-content\/uploads\/2020\/03\/danslatoile.png?fit=1167%2C485&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/portaileduc.net\/website\/wp-content\/uploads\/2020\/03\/danslatoile.png?fit=1167%2C485&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/portaileduc.net\/website\/wp-content\/uploads\/2020\/03\/danslatoile.png?fit=1167%2C485&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/portaileduc.net\/website\/wp-content\/uploads\/2020\/03\/danslatoile.png?fit=1167%2C485&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":4870,"url":"https:\/\/portaileduc.net\/website\/keep-pour-les-profs\/","url_meta":{"origin":49,"position":2},"title":"Keep pour les profs","author":"Maxime Duquesnoy","date":"6 janvier 2021","format":false,"excerpt":"Keep est une application de prise de notes tr\u00e8s simple, mais il ne s'agit pas que de notes textuelles. Vous pouvez l'utiliser pour enregistrer rapidement une image, cr\u00e9er un enregistrement audio ou cr\u00e9er une liste de t\u00e2ches rapide. Vous pouvez taguer, titre et coder par couleur vos notes comme bon\u2026","rel":"","context":"Dans &quot;Outils TICE&quot;","block_context":{"text":"Outils TICE","link":"https:\/\/portaileduc.net\/website\/category\/outils-tice\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/portaileduc.net\/website\/wp-content\/uploads\/2021\/01\/keep.png?fit=1200%2C624&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/portaileduc.net\/website\/wp-content\/uploads\/2021\/01\/keep.png?fit=1200%2C624&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/portaileduc.net\/website\/wp-content\/uploads\/2021\/01\/keep.png?fit=1200%2C624&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/portaileduc.net\/website\/wp-content\/uploads\/2021\/01\/keep.png?fit=1200%2C624&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/portaileduc.net\/website\/wp-content\/uploads\/2021\/01\/keep.png?fit=1200%2C624&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":4996,"url":"https:\/\/portaileduc.net\/website\/jouer-pour-apprendre-de-la-ludification-a-la-ludicisation\/","url_meta":{"origin":49,"position":3},"title":"Jouer pour apprendre: de la ludification \u00e0 la ludicisation","author":"Maxime Duquesnoy","date":"2 f\u00e9vrier 2021","format":false,"excerpt":"Ce dossier conjoint de Carrefour \u00e9ducation et de l'\u00c9cole branch\u00e9e, r\u00e9dig\u00e9 par Martine Rioux de l'\u00c9cole branch\u00e9e en collaboration avec\u00a0Alexandre Chenette, enseignant et conseiller p\u00e9dagogique au Service national du R\u00c9CIT, aborde la question de la ludification et la ludicisation. Ce qu\u2019est la ludification L\u2019impact sur les \u00e9l\u00e8ves Comment l\u2019int\u00e9grer \u00e0\u2026","rel":"","context":"Dans &quot;L'Atelier de Ludo&quot;","block_context":{"text":"L'Atelier de Ludo","link":"https:\/\/portaileduc.net\/website\/category\/latelier-de-ludo\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/portaileduc.net\/website\/wp-content\/uploads\/2021\/02\/144227050_10157501086375810_2936019903759731116_n.png?fit=940%2C788&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/portaileduc.net\/website\/wp-content\/uploads\/2021\/02\/144227050_10157501086375810_2936019903759731116_n.png?fit=940%2C788&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/portaileduc.net\/website\/wp-content\/uploads\/2021\/02\/144227050_10157501086375810_2936019903759731116_n.png?fit=940%2C788&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/portaileduc.net\/website\/wp-content\/uploads\/2021\/02\/144227050_10157501086375810_2936019903759731116_n.png?fit=940%2C788&ssl=1&resize=700%2C400 2x"},"classes":[]},{"id":367,"url":"https:\/\/portaileduc.net\/website\/services-aux-personnes-aide-soignant-aide-familial-sites-internet\/","url_meta":{"origin":49,"position":4},"title":"Services aux personnes &#8211; Aide-soignant \/ Aide-familial &#8211; Sites internet","author":"Maxime Duquesnoy","date":"11 ao\u00fbt 2016","format":false,"excerpt":"Devenir Aide-Soignant http:\/\/www.deveniraidesoignant.be\/ Ce site semble particuli\u00e8rement indiqu\u00e9 pour d\u00e9couvrir le m\u00e9tier mais il peut aussi servir \u00e0 diff\u00e9rents cours. Il propose des infos sur le m\u00e9tier, la formation, les \u00e9coles mais aussi par rapport \u00e0 l'agr\u00e9ment et au VISA. Une brochure en PDF est t\u00e9l\u00e9chargeable. \u00a0 FE.BI | Association\u2026","rel":"","context":"Dans &quot;Sant\u00e9 &amp; Services aux personnes&quot;","block_context":{"text":"Sant\u00e9 &amp; Services aux personnes","link":"https:\/\/portaileduc.net\/website\/category\/domaines-disciplines\/sante-services-aux-personnes\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/portaileduc.net\/website\/wp-content\/uploads\/2015\/07\/Services2.png?fit=590%2C359&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/portaileduc.net\/website\/wp-content\/uploads\/2015\/07\/Services2.png?fit=590%2C359&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/portaileduc.net\/website\/wp-content\/uploads\/2015\/07\/Services2.png?fit=590%2C359&ssl=1&resize=525%2C300 1.5x"},"classes":[]},{"id":5151,"url":"https:\/\/portaileduc.net\/website\/les-ressources-pedagogiques-deducam-pour-la-technologie\/","url_meta":{"origin":49,"position":5},"title":"Les ressources p\u00e9dagogiques d&rsquo;Educam pour la technologie","author":"Maxime Duquesnoy","date":"22 mars 2021","format":false,"excerpt":"EDUCAM a d\u00e9velopp\u00e9 une large gamme d\u2019outils didactiques pour vous soutenir les actions des enseignants de technologie. http:\/\/www.startyourfuture.be\/fr\/ Des posters - http:\/\/www.startyourfuture.be\/fr\/class\/pour-les-enseignants\/ Les posters techniques sont l'outil id\u00e9al pour aborder divers sujets techniques de mani\u00e8re ludique et didactique. Force et mouvement Force & mouvement Les ports de la d\u00e9cision Les\u2026","rel":"","context":"Dans &quot;Industrie et Technologie&quot;","block_context":{"text":"Industrie et Technologie","link":"https:\/\/portaileduc.net\/website\/category\/domaines-disciplines\/industrie-technologie\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/portaileduc.net\/website\/wp-content\/uploads\/2021\/03\/Capture-decran-2021-03-22-165201.png?fit=1200%2C702&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/portaileduc.net\/website\/wp-content\/uploads\/2021\/03\/Capture-decran-2021-03-22-165201.png?fit=1200%2C702&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/portaileduc.net\/website\/wp-content\/uploads\/2021\/03\/Capture-decran-2021-03-22-165201.png?fit=1200%2C702&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/portaileduc.net\/website\/wp-content\/uploads\/2021\/03\/Capture-decran-2021-03-22-165201.png?fit=1200%2C702&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/portaileduc.net\/website\/wp-content\/uploads\/2021\/03\/Capture-decran-2021-03-22-165201.png?fit=1200%2C702&ssl=1&resize=1050%2C600 3x"},"classes":[]}],"jetpack_likes_enabled":true,"_links":{"self":[{"href":"https:\/\/portaileduc.net\/website\/wp-json\/wp\/v2\/posts\/49","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/portaileduc.net\/website\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/portaileduc.net\/website\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/portaileduc.net\/website\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/portaileduc.net\/website\/wp-json\/wp\/v2\/comments?post=49"}],"version-history":[{"count":1,"href":"https:\/\/portaileduc.net\/website\/wp-json\/wp\/v2\/posts\/49\/revisions"}],"predecessor-version":[{"id":50,"href":"https:\/\/portaileduc.net\/website\/wp-json\/wp\/v2\/posts\/49\/revisions\/50"}],"wp:attachment":[{"href":"https:\/\/portaileduc.net\/website\/wp-json\/wp\/v2\/media?parent=49"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/portaileduc.net\/website\/wp-json\/wp\/v2\/categories?post=49"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/portaileduc.net\/website\/wp-json\/wp\/v2\/tags?post=49"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}