{"id":4579,"date":"2020-11-26T12:32:51","date_gmt":"2020-11-26T12:32:51","guid":{"rendered":"http:\/\/portaileduc.net\/website\/?p=4579"},"modified":"2020-11-26T12:34:20","modified_gmt":"2020-11-26T12:34:20","slug":"igrammaire","status":"publish","type":"post","link":"https:\/\/portaileduc.net\/website\/igrammaire\/","title":{"rendered":"iGrammaire"},"content":{"rendered":"<p><a href=\"http:\/\/portaileduc.net\/website\/igrammaire\/capture-decran-2020-11-26-133144\/\" rel=\"attachment wp-att-4581\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" class=\"alignright size-medium wp-image-4581\" src=\"https:\/\/i0.wp.com\/portaileduc.net\/website\/wp-content\/uploads\/2020\/11\/Capture-decran-2020-11-26-133144-300x160.png?resize=300%2C160\" alt=\"\" width=\"300\" height=\"160\" srcset=\"https:\/\/i0.wp.com\/portaileduc.net\/website\/wp-content\/uploads\/2020\/11\/Capture-decran-2020-11-26-133144.png?resize=300%2C160&amp;ssl=1 300w, https:\/\/i0.wp.com\/portaileduc.net\/website\/wp-content\/uploads\/2020\/11\/Capture-decran-2020-11-26-133144.png?resize=1024%2C545&amp;ssl=1 1024w, https:\/\/i0.wp.com\/portaileduc.net\/website\/wp-content\/uploads\/2020\/11\/Capture-decran-2020-11-26-133144.png?resize=768%2C409&amp;ssl=1 768w, https:\/\/i0.wp.com\/portaileduc.net\/website\/wp-content\/uploads\/2020\/11\/Capture-decran-2020-11-26-133144.png?resize=1536%2C817&amp;ssl=1 1536w, https:\/\/i0.wp.com\/portaileduc.net\/website\/wp-content\/uploads\/2020\/11\/Capture-decran-2020-11-26-133144.png?resize=50%2C27&amp;ssl=1 50w, https:\/\/i0.wp.com\/portaileduc.net\/website\/wp-content\/uploads\/2020\/11\/Capture-decran-2020-11-26-133144.png?w=1552&amp;ssl=1 1552w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a>iGrammaire est un logiciel gratuit d\u2019analyse syntaxique, permettant de manipuler et comprendre le fonctionnement de la phrase de base.<br \/>\nLe logiciel permet d&rsquo;analyser des phrases de base dans l&rsquo;ordre des mots canonique S &#8211; V &#8211; (C), qu&rsquo;elles soient simples ou complexes (uniquement par subordination).<\/p>\n<h3 style=\"text-align: center;\"><a href=\"https:\/\/www.igrammaire.com\/\">https:\/\/www.igrammaire.com\/<\/a><\/h3>\n<p>&nbsp;<\/p>\n<p>iGrammaire permet de travailler<\/p>\n<ul>\n<li>Les verbes conjugu\u00e9s : Trouver les verbes conjugu\u00e9s, les mots subordonnants, savoir reconna\u00eetre le verbe principal des secondaires<\/li>\n<li>Le sujet : Trouver le sujet du verbe principal avec la formulaire d&rsquo;extraction C&rsquo;est&#8230; Qui, et v\u00e9rifier gr\u00e2ce \u00e0 la pronominalisation<\/li>\n<li>Les compl\u00e9ments : D\u00e9couper les groupes compl\u00e9ments entre C&rsquo;est&#8230;Que, et faire les tests de suppression, d\u00e9placement et pronominalisation<\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n<h4>D\u00e9couvrir le logiciel<\/h4>\n<p><span class=\"embed-youtube\" style=\"text-align:center; display: block;\"><iframe loading=\"lazy\" class=\"youtube-player\" width=\"1140\" height=\"642\" src=\"https:\/\/www.youtube.com\/embed\/jdSjl7Kyhs4?version=3&#038;rel=1&#038;showsearch=0&#038;showinfo=1&#038;iv_load_policy=1&#038;fs=1&#038;hl=fr-FR&#038;autohide=2&#038;wmode=transparent\" allowfullscreen=\"true\" style=\"border:0;\" sandbox=\"allow-scripts allow-same-origin allow-popups allow-presentation allow-popups-to-escape-sandbox\"><\/iframe><\/span><\/p>\n<p>&nbsp;<\/p>\n<h4>Cr\u00e9er un corpus<\/h4>\n<p><span class=\"embed-youtube\" style=\"text-align:center; display: block;\"><iframe loading=\"lazy\" class=\"youtube-player\" width=\"1140\" height=\"642\" src=\"https:\/\/www.youtube.com\/embed\/1vNtEr-f0ps?version=3&#038;rel=1&#038;showsearch=0&#038;showinfo=1&#038;iv_load_policy=1&#038;fs=1&#038;hl=fr-FR&#038;autohide=2&#038;wmode=transparent\" allowfullscreen=\"true\" style=\"border:0;\" sandbox=\"allow-scripts allow-same-origin allow-popups allow-presentation allow-popups-to-escape-sandbox\"><\/iframe><\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>iGrammaire est un logiciel gratuit d\u2019analyse syntaxique, permettant de manipuler et comprendre le fonctionnement de la phrase de base. Le logiciel permet d&rsquo;analyser des phrases de base dans l&rsquo;ordre des mots canonique S &#8211; V &#8211; (C), qu&rsquo;elles soient simples ou complexes (uniquement par subordination). https:\/\/www.igrammaire.com\/ &nbsp; iGrammaire permet de travailler Les verbes conjugu\u00e9s : [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":4581,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[196,119],"tags":[],"class_list":["post-4579","post","type-post","status-publish","format-standard","has-post-thumbnail","category-outils-tice","category-francais-communication","czr-hentry"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/portaileduc.net\/website\/wp-content\/uploads\/2020\/11\/Capture-decran-2020-11-26-133144.png?fit=1552%2C826&ssl=1","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p6aRPV-1bR","jetpack-related-posts":[{"id":2790,"url":"https:\/\/portaileduc.net\/website\/la-bataille-navale-des-verbes\/","url_meta":{"origin":4579,"position":0},"title":"La bataille navale des verbes","author":"Maxime Duquesnoy","date":"27 mars 2020","format":false,"excerpt":"Sur le site https:\/\/fle.mondolinguo.com, vous pouvez retrouver \"La bataille navale des verbes\". Adaptation du\u00a0 \"touch\u00e9-coul\u00e9\" classique, le principe est simple : le jeu se joue \u00e0 deux joueurs, adversaires, qui ont chacun une grille avec une ligne \u00ab pronoms personnels \u00bb et une colonne \u00ab verbes \u00bb.\u00a0 Avant le d\u00e9but\u2026","rel":"","context":"Dans &quot;Fran\u00e7ais - Communication&quot;","block_context":{"text":"Fran\u00e7ais - Communication","link":"https:\/\/portaileduc.net\/website\/category\/domaines-disciplines\/francais-communication\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/portaileduc.net\/website\/wp-content\/uploads\/2020\/03\/Ige1.png?fit=1200%2C757&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/portaileduc.net\/website\/wp-content\/uploads\/2020\/03\/Ige1.png?fit=1200%2C757&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/portaileduc.net\/website\/wp-content\/uploads\/2020\/03\/Ige1.png?fit=1200%2C757&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/portaileduc.net\/website\/wp-content\/uploads\/2020\/03\/Ige1.png?fit=1200%2C757&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/portaileduc.net\/website\/wp-content\/uploads\/2020\/03\/Ige1.png?fit=1200%2C757&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":2493,"url":"https:\/\/portaileduc.net\/website\/quizlet\/","url_meta":{"origin":4579,"position":1},"title":"Quizlet &#8211; Des listes de mots deviennent des exercices","author":"Maxime Duquesnoy","date":"6 janvier 2020","format":false,"excerpt":"Quizlet permet de cr\u00e9er des listes de vocabulaire associ\u00e9es \u00e0 des s\u00e9ries d\u2019activit\u00e9s\u00a0 permettant l\u2019apprentissage et la m\u00e9morisation du lexique. Il est possible de lire, d\u2019entendre les mots (dict\u00e9s par un locuteur natif), de faire des jeux pour faciliter l\u2019apprentissage et enfin de faire des tests pour en v\u00e9rifier l\u2019acquisition.\u2026","rel":"","context":"Dans &quot;Outils TICE&quot;","block_context":{"text":"Outils TICE","link":"https:\/\/portaileduc.net\/website\/category\/outils-tice\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/portaileduc.net\/website\/wp-content\/uploads\/2020\/01\/22.png?resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/portaileduc.net\/website\/wp-content\/uploads\/2020\/01\/22.png?resize=350%2C200 1x, https:\/\/i0.wp.com\/portaileduc.net\/website\/wp-content\/uploads\/2020\/01\/22.png?resize=525%2C300 1.5x, https:\/\/i0.wp.com\/portaileduc.net\/website\/wp-content\/uploads\/2020\/01\/22.png?resize=700%2C400 2x"},"classes":[]},{"id":4096,"url":"https:\/\/portaileduc.net\/website\/inkscape\/","url_meta":{"origin":4579,"position":2},"title":"Inkscape, un logiciel libre de dessin vectoriel","author":"Maxime Duquesnoy","date":"13 ao\u00fbt 2020","format":false,"excerpt":"Inkscape est un logiciel de dessin vectoriel, c'est-\u00e0-dire un programme sp\u00e9cialement con\u00e7u pour l'\u00e9dition ou la cr\u00e9ation de graphisme vectoriel. Il s'agit d'un logiciel libre qui propose toute une panoplie d'outils. Inkscape permet d'\u00e9diter les fichiers standards SVG, d'exporter du PNG, PDF, etc. Il permet \u00e9galement l'\u00e9dition de PDF. La\u2026","rel":"","context":"Dans &quot;Outils TICE&quot;","block_context":{"text":"Outils TICE","link":"https:\/\/portaileduc.net\/website\/category\/outils-tice\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/portaileduc.net\/website\/wp-content\/uploads\/2020\/08\/Inkscape.png?fit=1200%2C824&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/portaileduc.net\/website\/wp-content\/uploads\/2020\/08\/Inkscape.png?fit=1200%2C824&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/portaileduc.net\/website\/wp-content\/uploads\/2020\/08\/Inkscape.png?fit=1200%2C824&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/portaileduc.net\/website\/wp-content\/uploads\/2020\/08\/Inkscape.png?fit=1200%2C824&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/portaileduc.net\/website\/wp-content\/uploads\/2020\/08\/Inkscape.png?fit=1200%2C824&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":6016,"url":"https:\/\/portaileduc.net\/website\/matilda\/","url_meta":{"origin":4579,"position":3},"title":"Matilda","author":"Maxime Duquesnoy","date":"11 f\u00e9vrier 2024","format":false,"excerpt":"Matilda est un moteur de recherche acad\u00e9mique qui vise \u00e0 am\u00e9liorer l'acc\u00e8s aux r\u00e9f\u00e9rences et citations souvent n\u00e9glig\u00e9es dans la recherche, se positionnant comme une alternative \u00e0 des moteurs de recherche tels que Google Scholar. Fond\u00e9 sur des donn\u00e9es ouvertes et du logiciel libre, Matilda favorise l'\u00e9gal traitement des textes\u2026","rel":"","context":"Dans &quot;Ressources bibliographiques&quot;","block_context":{"text":"Ressources bibliographiques","link":"https:\/\/portaileduc.net\/website\/category\/bibliographie\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/portaileduc.net\/website\/wp-content\/uploads\/2024\/02\/Green-And-Blue-Modern-Learn-English-Quickly-Youtube-Thumbnail-1024-x-684-px.png?fit=1024%2C684&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/portaileduc.net\/website\/wp-content\/uploads\/2024\/02\/Green-And-Blue-Modern-Learn-English-Quickly-Youtube-Thumbnail-1024-x-684-px.png?fit=1024%2C684&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/portaileduc.net\/website\/wp-content\/uploads\/2024\/02\/Green-And-Blue-Modern-Learn-English-Quickly-Youtube-Thumbnail-1024-x-684-px.png?fit=1024%2C684&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/portaileduc.net\/website\/wp-content\/uploads\/2024\/02\/Green-And-Blue-Modern-Learn-English-Quickly-Youtube-Thumbnail-1024-x-684-px.png?fit=1024%2C684&ssl=1&resize=700%2C400 2x"},"classes":[]},{"id":596,"url":"https:\/\/portaileduc.net\/website\/creer-des-mots-croises-des-mots-caches\/","url_meta":{"origin":4579,"position":4},"title":"Cr\u00e9er des mots-crois\u00e9s et de mots-cach\u00e9s","author":"Maxime Duquesnoy","date":"1 juillet 2024","format":false,"excerpt":"Cr\u00e9er des grilles de mots crois\u00e9s CROSSWORDLABS \u2013 Cr\u00e9er une grille de mots crois\u00e9s https:\/\/crosswordlabs.com\/ Crossword Puzzle pour cr\u00e9er des mots crois\u00e9s Ce g\u00e9n\u00e9rateur de grilles de mots crois\u00e9s permet de choisir parmi plusieurs mod\u00e8les avant de l\u2019imprimer au format PDF. https:\/\/www.education.com\/worksheet-generator\/reading\/crossword-puzzle\/ Mots entrecrois\u00e9s Mots entrecrois\u00e9s\u00a0est un outil permettant la\u2026","rel":"","context":"Dans &quot;Outils p\u00e9dagogiques&quot;","block_context":{"text":"Outils p\u00e9dagogiques","link":"https:\/\/portaileduc.net\/website\/category\/outils-pedagogiques\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/portaileduc.net\/website\/wp-content\/uploads\/2020\/11\/Green-And-Blue-Modern-Learn-English-Quickly-Youtube-Thumbnail-1.jpg?fit=1200%2C675&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/portaileduc.net\/website\/wp-content\/uploads\/2020\/11\/Green-And-Blue-Modern-Learn-English-Quickly-Youtube-Thumbnail-1.jpg?fit=1200%2C675&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/portaileduc.net\/website\/wp-content\/uploads\/2020\/11\/Green-And-Blue-Modern-Learn-English-Quickly-Youtube-Thumbnail-1.jpg?fit=1200%2C675&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/portaileduc.net\/website\/wp-content\/uploads\/2020\/11\/Green-And-Blue-Modern-Learn-English-Quickly-Youtube-Thumbnail-1.jpg?fit=1200%2C675&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/portaileduc.net\/website\/wp-content\/uploads\/2020\/11\/Green-And-Blue-Modern-Learn-English-Quickly-Youtube-Thumbnail-1.jpg?fit=1200%2C675&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":6053,"url":"https:\/\/portaileduc.net\/website\/magicschool\/","url_meta":{"origin":4579,"position":5},"title":"MagicSchool","author":"Maxime Duquesnoy","date":"18 f\u00e9vrier 2024","format":false,"excerpt":"MagicSchool.ai est une plateforme qui propose aux enseignants un ensemble d'outils bas\u00e9s sur l'IA. Ces outils permettent de cr\u00e9er du contenu original, de g\u00e9n\u00e9rer des \u00e9valuations interactives, de fournir des feedbacks personnalis\u00e9s, d'analyser les donn\u00e9es des \u00e9l\u00e8ves, et d'am\u00e9liorer ses comp\u00e9tences p\u00e9dagogiques. https:\/\/app.magicschool.ai\/ MagicSchool propose un outil d'intelligence artificielle clairement\u2026","rel":"","context":"Dans &quot;Intelligence artificielle&quot;","block_context":{"text":"Intelligence artificielle","link":"https:\/\/portaileduc.net\/website\/category\/ia\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/portaileduc.net\/website\/wp-content\/uploads\/2024\/02\/Green-And-Blue-Modern-Learn-English-Quickly-Youtube-Thumbnail-1-1.png?fit=1200%2C675&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/portaileduc.net\/website\/wp-content\/uploads\/2024\/02\/Green-And-Blue-Modern-Learn-English-Quickly-Youtube-Thumbnail-1-1.png?fit=1200%2C675&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/portaileduc.net\/website\/wp-content\/uploads\/2024\/02\/Green-And-Blue-Modern-Learn-English-Quickly-Youtube-Thumbnail-1-1.png?fit=1200%2C675&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/portaileduc.net\/website\/wp-content\/uploads\/2024\/02\/Green-And-Blue-Modern-Learn-English-Quickly-Youtube-Thumbnail-1-1.png?fit=1200%2C675&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/portaileduc.net\/website\/wp-content\/uploads\/2024\/02\/Green-And-Blue-Modern-Learn-English-Quickly-Youtube-Thumbnail-1-1.png?fit=1200%2C675&ssl=1&resize=1050%2C600 3x"},"classes":[]}],"jetpack_likes_enabled":true,"_links":{"self":[{"href":"https:\/\/portaileduc.net\/website\/wp-json\/wp\/v2\/posts\/4579","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/portaileduc.net\/website\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/portaileduc.net\/website\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/portaileduc.net\/website\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/portaileduc.net\/website\/wp-json\/wp\/v2\/comments?post=4579"}],"version-history":[{"count":3,"href":"https:\/\/portaileduc.net\/website\/wp-json\/wp\/v2\/posts\/4579\/revisions"}],"predecessor-version":[{"id":4583,"href":"https:\/\/portaileduc.net\/website\/wp-json\/wp\/v2\/posts\/4579\/revisions\/4583"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/portaileduc.net\/website\/wp-json\/wp\/v2\/media\/4581"}],"wp:attachment":[{"href":"https:\/\/portaileduc.net\/website\/wp-json\/wp\/v2\/media?parent=4579"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/portaileduc.net\/website\/wp-json\/wp\/v2\/categories?post=4579"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/portaileduc.net\/website\/wp-json\/wp\/v2\/tags?post=4579"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}