{"id":3795,"date":"2020-07-21T05:19:09","date_gmt":"2020-07-21T05:19:09","guid":{"rendered":"http:\/\/portaileduc.net\/website\/?p=3795"},"modified":"2020-07-21T05:19:09","modified_gmt":"2020-07-21T05:19:09","slug":"moodle-organiser-un-examen-ecrit-non-surveille-avec-un-test","status":"publish","type":"post","link":"https:\/\/portaileduc.net\/website\/moodle-organiser-un-examen-ecrit-non-surveille-avec-un-test\/","title":{"rendered":"Moodle &#8211; Organiser un examen \u00e9crit non surveill\u00e9 avec un test"},"content":{"rendered":"<p><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" class=\"wp-image-3796 alignright\" src=\"https:\/\/i0.wp.com\/portaileduc.net\/website\/wp-content\/uploads\/2020\/07\/Annotation-2020-07-21-071825-1024x536.png?resize=200%2C105\" alt=\"\" width=\"200\" height=\"105\" srcset=\"https:\/\/i0.wp.com\/portaileduc.net\/website\/wp-content\/uploads\/2020\/07\/Annotation-2020-07-21-071825.png?resize=1024%2C536&amp;ssl=1 1024w, https:\/\/i0.wp.com\/portaileduc.net\/website\/wp-content\/uploads\/2020\/07\/Annotation-2020-07-21-071825.png?resize=300%2C157&amp;ssl=1 300w, https:\/\/i0.wp.com\/portaileduc.net\/website\/wp-content\/uploads\/2020\/07\/Annotation-2020-07-21-071825.png?resize=768%2C402&amp;ssl=1 768w, https:\/\/i0.wp.com\/portaileduc.net\/website\/wp-content\/uploads\/2020\/07\/Annotation-2020-07-21-071825.png?resize=1536%2C803&amp;ssl=1 1536w, https:\/\/i0.wp.com\/portaileduc.net\/website\/wp-content\/uploads\/2020\/07\/Annotation-2020-07-21-071825.png?resize=50%2C26&amp;ssl=1 50w, https:\/\/i0.wp.com\/portaileduc.net\/website\/wp-content\/uploads\/2020\/07\/Annotation-2020-07-21-071825.png?w=1612&amp;ssl=1 1612w\" sizes=\"auto, (max-width: 200px) 100vw, 200px\" \/>Ce genial.ly pr\u00e9sente des c<span class=\"css-901oao css-16my406 r-1qd0xha r-ad9z0x r-bcqeeo r-qvutc0\">onseils de configuration, questions et r\u00e9ponses, probl\u00e8mes et solutions pour o<\/span><span class=\"css-901oao css-16my406 r-1qd0xha r-ad9z0x r-bcqeeo r-qvutc0\">rganiser un examen \u00e9crit non surveill\u00e9 avec un test Moodle<\/span><\/p>\n<p>Lien : <a href=\"https:\/\/view.genial.ly\/5efd9c25e16c3d0d2b110a17\">https:\/\/view.genial.ly\/5efd9c25e16c3d0d2b110a17<\/a><\/p>\n<p>&nbsp;<\/p>\n<div style=\"width: 100%;\">\n<div style=\"position: relative; padding-bottom: 56.25%; padding-top: 0; height: 0;\"><iframe loading=\"lazy\" style=\"position: absolute; top: 0; left: 0; width: 100%; height: 100%;\" src=\"https:\/\/view.genial.ly\/5efd9c25e16c3d0d2b110a17\" width=\"1200px\" height=\"675px\" frameborder=\"0\" scrolling=\"yes\" allowfullscreen=\"allowfullscreen\"><\/iframe><\/div>\n<\/div>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ce genial.ly pr\u00e9sente des conseils de configuration, questions et r\u00e9ponses, probl\u00e8mes et solutions pour organiser un examen \u00e9crit non surveill\u00e9 avec un test Moodle Lien : https:\/\/view.genial.ly\/5efd9c25e16c3d0d2b110a17 &nbsp; &nbsp;<\/p>\n","protected":false},"author":2,"featured_media":3796,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[227],"tags":[],"class_list":["post-3795","post","type-post","status-publish","format-standard","has-post-thumbnail","category-moodle","czr-hentry"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/portaileduc.net\/website\/wp-content\/uploads\/2020\/07\/Annotation-2020-07-21-071825.png?fit=1612%2C843&ssl=1","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p6aRPV-Zd","jetpack-related-posts":[{"id":2707,"url":"https:\/\/portaileduc.net\/website\/moodle-les-tests\/","url_meta":{"origin":3795,"position":0},"title":"MOODLE &#8211; Les tests","author":"Maxime Duquesnoy","date":"20 mars 2020","format":false,"excerpt":"Le module d'activit\u00e9 test permet \u00e0 l'enseignant de cr\u00e9er des tests comportant des questions de divers types, notamment des questions \u00e0 choix multiples, vrai-faux, de correspondances, \u00e0 r\u00e9ponses courtes ou calcul\u00e9es. L'enseignant peut autoriser plusieurs tentatives pour un test, les questions \u00e9tant m\u00e9lang\u00e9es ou choisies al\u00e9atoirement dans une banque de\u2026","rel":"","context":"Dans &quot;Moodle&quot;","block_context":{"text":"Moodle","link":"https:\/\/portaileduc.net\/website\/category\/numerique-education\/moodle\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/portaileduc.net\/website\/wp-content\/uploads\/2020\/03\/Moodle.jpg?fit=830%2C400&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/portaileduc.net\/website\/wp-content\/uploads\/2020\/03\/Moodle.jpg?fit=830%2C400&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/portaileduc.net\/website\/wp-content\/uploads\/2020\/03\/Moodle.jpg?fit=830%2C400&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/portaileduc.net\/website\/wp-content\/uploads\/2020\/03\/Moodle.jpg?fit=830%2C400&ssl=1&resize=700%2C400 2x"},"classes":[]},{"id":3823,"url":"https:\/\/portaileduc.net\/website\/moodle-plugin-bigbluebutton\/","url_meta":{"origin":3795,"position":1},"title":"Moodle &#8211; Plugin BigBlueButton","author":"Maxime Duquesnoy","date":"21 juillet 2020","format":false,"excerpt":"Les plugins additionnels BigBlueButton, proposent une activit\u00e9 (avec en compl\u00e9ment la possibilit\u00e9 d'enregistrer les sessions) de classe virtuelle et\/ou webconf\u00e9rence. https:\/\/moodle.org\/plugins\/mod_bigbluebuttonbn","rel":"","context":"Dans &quot;Moodle&quot;","block_context":{"text":"Moodle","link":"https:\/\/portaileduc.net\/website\/category\/numerique-education\/moodle\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/portaileduc.net\/website\/wp-content\/uploads\/2020\/07\/BigBlueButton-2.jpg?fit=1024%2C512&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/portaileduc.net\/website\/wp-content\/uploads\/2020\/07\/BigBlueButton-2.jpg?fit=1024%2C512&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/portaileduc.net\/website\/wp-content\/uploads\/2020\/07\/BigBlueButton-2.jpg?fit=1024%2C512&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/portaileduc.net\/website\/wp-content\/uploads\/2020\/07\/BigBlueButton-2.jpg?fit=1024%2C512&ssl=1&resize=700%2C400 2x"},"classes":[]},{"id":3832,"url":"https:\/\/portaileduc.net\/website\/moodle-plugin-bigbluebutton-2\/","url_meta":{"origin":3795,"position":2},"title":"Moodle &#8211; Plugin Wooclap","author":"Maxime Duquesnoy","date":"21 juillet 2020","format":false,"excerpt":"Le plugin Wooclap permet, via Moodle, d'acc\u00e9der \u00e0 une \u201cactivit\u00e9 Wooclap\u201d pour cr\u00e9er du contenu Wooclap au sein de Moodle. De plus, les r\u00e9sultats d\u2019un \u00e9v\u00e9nement Wooclap peuvent \u00eatre synchronis\u00e9s sur Moodle, y donnant aux enseignants acc\u00e8s aux r\u00e9sultats individuels des \u00e9tudiants. https:\/\/moodle.org\/plugins\/mod_wooclap D\u00e9couvrez Comment int\u00e9grer vos questions Moodle au\u2026","rel":"","context":"Dans &quot;Moodle&quot;","block_context":{"text":"Moodle","link":"https:\/\/portaileduc.net\/website\/category\/numerique-education\/moodle\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/portaileduc.net\/website\/wp-content\/uploads\/2020\/07\/1.png?fit=800%2C562&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/portaileduc.net\/website\/wp-content\/uploads\/2020\/07\/1.png?fit=800%2C562&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/portaileduc.net\/website\/wp-content\/uploads\/2020\/07\/1.png?fit=800%2C562&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/portaileduc.net\/website\/wp-content\/uploads\/2020\/07\/1.png?fit=800%2C562&ssl=1&resize=700%2C400 2x"},"classes":[]},{"id":2684,"url":"https:\/\/portaileduc.net\/website\/moodle-utiliser-les-outils-de-cours\/","url_meta":{"origin":3795,"position":3},"title":"MOODLE &#8211; Utiliser les outils de cours","author":"Maxime Duquesnoy","date":"20 mars 2020","format":false,"excerpt":"Les outils de cours sont r\u00e9partis dans 4 cat\u00e9gories : les ressources qui permettent de diffuser des contenus; les activit\u00e9s qui permettent de proposer des activit\u00e9s aux \u00e9tudiants; les outils d'administration du cours qui permettent de g\u00e9rer les inscriptions au cours, de g\u00e9rer les groupes, ... les blocs qui permettent\u2026","rel":"","context":"Dans &quot;Moodle&quot;","block_context":{"text":"Moodle","link":"https:\/\/portaileduc.net\/website\/category\/numerique-education\/moodle\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/portaileduc.net\/website\/wp-content\/uploads\/2020\/03\/Moodle.jpg?fit=830%2C400&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/portaileduc.net\/website\/wp-content\/uploads\/2020\/03\/Moodle.jpg?fit=830%2C400&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/portaileduc.net\/website\/wp-content\/uploads\/2020\/03\/Moodle.jpg?fit=830%2C400&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/portaileduc.net\/website\/wp-content\/uploads\/2020\/03\/Moodle.jpg?fit=830%2C400&ssl=1&resize=700%2C400 2x"},"classes":[]},{"id":2714,"url":"https:\/\/portaileduc.net\/website\/moodle-comment-rendre-mon-cours-plus-organise-et-ergonomique\/","url_meta":{"origin":3795,"position":4},"title":"MOODLE &#8211; Comment rendre mon cours plus organis\u00e9 et ergonomique?","author":"Maxime Duquesnoy","date":"20 mars 2020","format":false,"excerpt":"D\u00e9couvrez cette vid\u00e9o du CPFB pour vous permettre de rendre votre cours sur Moodle organis\u00e9 et ergonomique. \u00a0 https:\/\/youtu.be\/AdVWfVZFSLo","rel":"","context":"Dans &quot;Moodle&quot;","block_context":{"text":"Moodle","link":"https:\/\/portaileduc.net\/website\/category\/numerique-education\/moodle\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/portaileduc.net\/website\/wp-content\/uploads\/2020\/03\/Moodle.jpg?fit=830%2C400&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/portaileduc.net\/website\/wp-content\/uploads\/2020\/03\/Moodle.jpg?fit=830%2C400&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/portaileduc.net\/website\/wp-content\/uploads\/2020\/03\/Moodle.jpg?fit=830%2C400&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/portaileduc.net\/website\/wp-content\/uploads\/2020\/03\/Moodle.jpg?fit=830%2C400&ssl=1&resize=700%2C400 2x"},"classes":[]},{"id":2700,"url":"https:\/\/portaileduc.net\/website\/moodle-creer-parametrer-et-utiliser-un-forum\/","url_meta":{"origin":3795,"position":5},"title":"MOODLE &#8211; Cr\u00e9er, param\u00e9trer et utiliser un forum","author":"Maxime Duquesnoy","date":"20 mars 2020","format":false,"excerpt":"Un forum est un outil de discussion asynchrone par \u00e9crit. A la diff\u00e9rence du courrier \u00e9lectronique, le forum place la discussion dans un espace public ou semi-public. Les forums sont souvent vus comme des espaces de questions-r\u00e9ponses. Mais ils peuvent \u00eatre exploit\u00e9s de mani\u00e8re p\u00e9dagogique : avant le cours, pour\u2026","rel":"","context":"Dans &quot;Moodle&quot;","block_context":{"text":"Moodle","link":"https:\/\/portaileduc.net\/website\/category\/numerique-education\/moodle\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/portaileduc.net\/website\/wp-content\/uploads\/2020\/03\/Moodle.jpg?fit=830%2C400&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/portaileduc.net\/website\/wp-content\/uploads\/2020\/03\/Moodle.jpg?fit=830%2C400&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/portaileduc.net\/website\/wp-content\/uploads\/2020\/03\/Moodle.jpg?fit=830%2C400&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/portaileduc.net\/website\/wp-content\/uploads\/2020\/03\/Moodle.jpg?fit=830%2C400&ssl=1&resize=700%2C400 2x"},"classes":[]}],"jetpack_likes_enabled":true,"_links":{"self":[{"href":"https:\/\/portaileduc.net\/website\/wp-json\/wp\/v2\/posts\/3795","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/portaileduc.net\/website\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/portaileduc.net\/website\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/portaileduc.net\/website\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/portaileduc.net\/website\/wp-json\/wp\/v2\/comments?post=3795"}],"version-history":[{"count":1,"href":"https:\/\/portaileduc.net\/website\/wp-json\/wp\/v2\/posts\/3795\/revisions"}],"predecessor-version":[{"id":3797,"href":"https:\/\/portaileduc.net\/website\/wp-json\/wp\/v2\/posts\/3795\/revisions\/3797"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/portaileduc.net\/website\/wp-json\/wp\/v2\/media\/3796"}],"wp:attachment":[{"href":"https:\/\/portaileduc.net\/website\/wp-json\/wp\/v2\/media?parent=3795"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/portaileduc.net\/website\/wp-json\/wp\/v2\/categories?post=3795"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/portaileduc.net\/website\/wp-json\/wp\/v2\/tags?post=3795"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}