{"id":2505,"date":"2020-01-12T17:20:42","date_gmt":"2020-01-12T17:20:42","guid":{"rendered":"http:\/\/portaileduc.net\/website\/?p=2505"},"modified":"2021-12-12T07:00:00","modified_gmt":"2021-12-12T07:00:00","slug":"dixit","status":"publish","type":"post","link":"https:\/\/portaileduc.net\/website\/dixit\/","title":{"rendered":"DIXIT"},"content":{"rendered":"<p>Dixit est un jeu de soci\u00e9t\u00e9 qui fait appel \u00e0 l\u2019imagination. Il se joue en groupe et favorise la cr\u00e9ativit\u00e9.<\/p>\n<p>&nbsp;<\/p>\n<p>[pdf-embedder url=\u00a0\u00bbhttp:\/\/portaileduc.net\/website\/wp-content\/uploads\/2020\/01\/DIXIT.pdf\u00a0\u00bb]<\/p>\n<p>&nbsp;<\/p>\n<p>Retrouvez \u00e9galement la fiche propos\u00e9e par l&rsquo;Universit\u00e9 de Lorraine<\/p>\n<blockquote class=\"wp-embedded-content\" data-secret=\"ww85eLjSOP\"><p><a href=\"https:\/\/sup.univ-lorraine.fr\/dixit\/\">Dixit<\/a><\/p><\/blockquote>\n<p><iframe loading=\"lazy\" class=\"wp-embedded-content\" sandbox=\"allow-scripts\" security=\"restricted\" style=\"position: absolute; clip: rect(1px, 1px, 1px, 1px);\" title=\"\u00ab\u00a0Dixit\u00a0\u00bb &#8212; DACIP\" src=\"https:\/\/sup.univ-lorraine.fr\/dixit\/embed\/#?secret=ww85eLjSOP\" data-secret=\"ww85eLjSOP\" width=\"600\" height=\"338\" frameborder=\"0\" marginwidth=\"0\" marginheight=\"0\" scrolling=\"no\"><\/iframe><\/p>\n<p>[pdfjs-viewer url=\u00a0\u00bbhttps:\/\/portaileduc.net\/website\/wp-content\/uploads\/2020\/01\/FOC-ludopedagogie-dixit-teachlab-dacip-univ-lorraine.pdf\u00a0\u00bb attachment_id=\u00a0\u00bb5440&Prime; viewer_width=100% viewer_height=800px fullscreen=true download=true print=true]<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Dixit est un jeu de soci\u00e9t\u00e9 qui fait appel \u00e0 l\u2019imagination. Il se joue en groupe et favorise la cr\u00e9ativit\u00e9. &nbsp; [pdf-embedder url=\u00a0\u00bbhttp:\/\/portaileduc.net\/website\/wp-content\/uploads\/2020\/01\/DIXIT.pdf\u00a0\u00bb] &nbsp; Retrouvez \u00e9galement la fiche propos\u00e9e par l&rsquo;Universit\u00e9 de Lorraine Dixit [pdfjs-viewer url=\u00a0\u00bbhttps:\/\/portaileduc.net\/website\/wp-content\/uploads\/2020\/01\/FOC-ludopedagogie-dixit-teachlab-dacip-univ-lorraine.pdf\u00a0\u00bb attachment_id=\u00a0\u00bb5440&Prime; viewer_width=100% viewer_height=800px fullscreen=true download=true print=true]<\/p>\n","protected":false},"author":2,"featured_media":2506,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[218],"tags":[],"class_list":["post-2505","post","type-post","status-publish","format-standard","has-post-thumbnail","category-latelier-de-ludo","czr-hentry"],"jetpack_publicize_connections":[],"jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/s6aRPV-dixit","jetpack-related-posts":[{"id":5876,"url":"https:\/\/portaileduc.net\/website\/photolangage\/","url_meta":{"origin":2505,"position":0},"title":"Photolangage","author":"Maxime Duquesnoy","date":"29 d\u00e9cembre 2023","format":false,"excerpt":"Le Photolangage\u00ae (Baptiste, Belisle, Pechenart et Vacheret, 1991) est une m\u00e9thode qui a pour objectif principal de permettre la prise de parole des personnes lorsqu\u2019elles doivent s\u2019exprimer en groupe. En s\u00e9lectionnant la photographie qui correspond le mieux \u00e0 leur ressenti, elle aide les participants \u00e0 verbaliser leur exp\u00e9rience, \u00e0 prendre\u2026","rel":"","context":"Dans &quot;Outils p\u00e9dagogiques&quot;","block_context":{"text":"Outils p\u00e9dagogiques","link":"https:\/\/portaileduc.net\/website\/category\/outils-pedagogiques\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/portaileduc.net\/website\/wp-content\/uploads\/2023\/12\/Green-And-Blue-Modern-Learn-English-Quickly-Youtube-Thumbnail.jpg?fit=1200%2C675&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/portaileduc.net\/website\/wp-content\/uploads\/2023\/12\/Green-And-Blue-Modern-Learn-English-Quickly-Youtube-Thumbnail.jpg?fit=1200%2C675&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/portaileduc.net\/website\/wp-content\/uploads\/2023\/12\/Green-And-Blue-Modern-Learn-English-Quickly-Youtube-Thumbnail.jpg?fit=1200%2C675&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/portaileduc.net\/website\/wp-content\/uploads\/2023\/12\/Green-And-Blue-Modern-Learn-English-Quickly-Youtube-Thumbnail.jpg?fit=1200%2C675&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/portaileduc.net\/website\/wp-content\/uploads\/2023\/12\/Green-And-Blue-Modern-Learn-English-Quickly-Youtube-Thumbnail.jpg?fit=1200%2C675&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":5621,"url":"https:\/\/portaileduc.net\/website\/les-decodeuses-du-numerique\/","url_meta":{"origin":2505,"position":1},"title":"Les d\u00e9codeuses du num\u00e9rique","author":"Maxime Duquesnoy","date":"27 mars 2023","format":false,"excerpt":"La bande dessin\u00e9e \u00ab Les d\u00e9codeuses du num\u00e9rique \u00bb, ainsi que des ressources compl\u00e9mentaires\u00a0vise \u00e0 \u00ab mettre en avant la diversit\u00e9 des recherches en sciences du num\u00e9rique et contribuer \u00e0 briser les st\u00e9r\u00e9otypes qui dissuadent les femmes de s\u2019engager dans cette voie \u00bb. Pour en faciliter l\u2019utilisation dans les lyc\u00e9es,\u2026","rel":"","context":"Dans &quot;Education au num\u00e9rique&quot;","block_context":{"text":"Education au num\u00e9rique","link":"https:\/\/portaileduc.net\/website\/category\/education-au-numerique\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/portaileduc.net\/website\/wp-content\/uploads\/2023\/03\/Banniere_page_bande_dessinee-2.png?fit=280%2C200&ssl=1&resize=350%2C200","width":350,"height":200},"classes":[]},{"id":5109,"url":"https:\/\/portaileduc.net\/website\/intervention-enigmatik-usages-detournements-et-reappropriation-du-jeu\/","url_meta":{"origin":2505,"position":2},"title":"Intervention EN\u2019iGmatik &#8211; Usages, d\u00e9tournements et r\u00e9appropriation du jeu","author":"Maxime Duquesnoy","date":"9 mars 2021","format":false,"excerpt":"Nous vous proposons de retrouver notre intervention \u00e0 l\u2019occasion du salon EN\u2019iGmatik sur le th\u00e8me Usages, d\u00e9tournements et r\u00e9appropriation du jeu Qu\u2019il s\u2019agisse de d\u00e9velopper la cr\u00e9ativit\u00e9, la prise de parole ou encore l\u2019acquisition de connaissances, les jeux peuvent apporter une approche diff\u00e9rente dans le cadre des apprentissages. Certains n\u00e9cessitent,\u2026","rel":"","context":"Dans &quot;L'Atelier de Ludo&quot;","block_context":{"text":"L'Atelier de Ludo","link":"https:\/\/portaileduc.net\/website\/category\/latelier-de-ludo\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/portaileduc.net\/website\/wp-content\/uploads\/2021\/03\/USAGES-DETOURNEMENTS-REAPPROPRIATION-DU-JEU.png?fit=1200%2C675&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/portaileduc.net\/website\/wp-content\/uploads\/2021\/03\/USAGES-DETOURNEMENTS-REAPPROPRIATION-DU-JEU.png?fit=1200%2C675&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/portaileduc.net\/website\/wp-content\/uploads\/2021\/03\/USAGES-DETOURNEMENTS-REAPPROPRIATION-DU-JEU.png?fit=1200%2C675&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/portaileduc.net\/website\/wp-content\/uploads\/2021\/03\/USAGES-DETOURNEMENTS-REAPPROPRIATION-DU-JEU.png?fit=1200%2C675&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/portaileduc.net\/website\/wp-content\/uploads\/2021\/03\/USAGES-DETOURNEMENTS-REAPPROPRIATION-DU-JEU.png?fit=1200%2C675&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":5618,"url":"https:\/\/portaileduc.net\/website\/le-kit-cyberenjeux\/","url_meta":{"origin":2505,"position":3},"title":"Le kit CyberEnJeux","author":"Maxime Duquesnoy","date":"27 mars 2023","format":false,"excerpt":"Le kit CyberEnJeux constitue un support pour la construction d\u2019une s\u00e9quence p\u00e9dagogique d\u00e9di\u00e9e \u00e0 la formation de leurs \u00e9l\u00e8ves \u00e0 la cybers\u00e9curit\u00e9 par la conception de jeux. Quatre types de fiches sont mises \u00e0 disposition : organisation, cybers\u00e9curit\u00e9, jeux, objectifs p\u00e9dagogiques. Compos\u00e9 de fiches th\u00e9matiques et p\u00e9dagogiques ainsi que de\u2026","rel":"","context":"Dans &quot;Education au num\u00e9rique&quot;","block_context":{"text":"Education au num\u00e9rique","link":"https:\/\/portaileduc.net\/website\/category\/education-au-numerique\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/portaileduc.net\/website\/wp-content\/uploads\/2023\/03\/E-ScHuKWUAcpUq-1.jpg?fit=1200%2C822&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/portaileduc.net\/website\/wp-content\/uploads\/2023\/03\/E-ScHuKWUAcpUq-1.jpg?fit=1200%2C822&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/portaileduc.net\/website\/wp-content\/uploads\/2023\/03\/E-ScHuKWUAcpUq-1.jpg?fit=1200%2C822&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/portaileduc.net\/website\/wp-content\/uploads\/2023\/03\/E-ScHuKWUAcpUq-1.jpg?fit=1200%2C822&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/portaileduc.net\/website\/wp-content\/uploads\/2023\/03\/E-ScHuKWUAcpUq-1.jpg?fit=1200%2C822&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":3991,"url":"https:\/\/portaileduc.net\/website\/leval-a-distance-un-guide-pratique-pour-transposer-levaluation-a-distance\/","url_meta":{"origin":2505,"position":4},"title":"L\u2019\u00e9val\u2019 \u00e0 distance &#8211; Un guide pratique pour transposer l&rsquo;\u00e9valuation \u00e0 distance","author":"Maxime Duquesnoy","date":"28 juillet 2020","format":false,"excerpt":"Sur son site, l'Institut de D\u00e9veloppement et d'Innovation P\u00e9dagogiques propose de nombreuses pistes et ressources sur l'\u00e9valuation (\u00e0 distance). On retiendra, notamment, leur guide \"L\u2019\u00e9val\u2019 \u00e0 distance\" qui propose plusieurs pistes et explore les types d'\u00e9valuation. A d\u00e9couvrir sur https:\/\/idip.unistra.fr\/wp-content\/uploads\/2020\/04\/Types_evaluations.pdf \u00a0 [pdfjs-viewer url=\"http%3A%2F%2Fportaileduc.net%2Fwebsite%2Fwp-content%2Fuploads%2F2020%2F07%2FTypes_evaluations.pdf\" viewer_width=100% viewer_height=800px fullscreen=true download=true print=true]","rel":"","context":"Dans &quot;Evaluation et docimologie&quot;","block_context":{"text":"Evaluation et docimologie","link":"https:\/\/portaileduc.net\/website\/category\/psychologie-pedagogie-didactique\/levaluation\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/portaileduc.net\/website\/wp-content\/uploads\/2020\/07\/Eval_distance.png?fit=851%2C1200&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/portaileduc.net\/website\/wp-content\/uploads\/2020\/07\/Eval_distance.png?fit=851%2C1200&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/portaileduc.net\/website\/wp-content\/uploads\/2020\/07\/Eval_distance.png?fit=851%2C1200&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/portaileduc.net\/website\/wp-content\/uploads\/2020\/07\/Eval_distance.png?fit=851%2C1200&ssl=1&resize=700%2C400 2x"},"classes":[]},{"id":5711,"url":"https:\/\/portaileduc.net\/website\/lart-du-prompt-dialoguer-avec-lia\/","url_meta":{"origin":2505,"position":5},"title":"L&rsquo;art du prompt, dialoguer avec l&rsquo;IA","author":"Maxime Duquesnoy","date":"27 mars 2023","format":false,"excerpt":"L\u2019art du prompt 101, Guide pour les personnes enseignantes Dans ce guide, l\u2019auteur propose une explication simple et bien illustr\u00e9e de comment g\u00e9n\u00e9rer du mat\u00e9riel p\u00e9dagogique unique et significatif en utilisant ChatGPT. Il souligne l'importance d'\u00e9crire de bonnes instructions pour bien profiter de l\u2019outil ChatGPT dans le cadre du travail\u2026","rel":"","context":"Dans &quot;Intelligence artificielle&quot;","block_context":{"text":"Intelligence artificielle","link":"https:\/\/portaileduc.net\/website\/category\/ia\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/portaileduc.net\/website\/wp-content\/uploads\/2023\/03\/1-1.png?fit=1200%2C675&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/portaileduc.net\/website\/wp-content\/uploads\/2023\/03\/1-1.png?fit=1200%2C675&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/portaileduc.net\/website\/wp-content\/uploads\/2023\/03\/1-1.png?fit=1200%2C675&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/portaileduc.net\/website\/wp-content\/uploads\/2023\/03\/1-1.png?fit=1200%2C675&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/portaileduc.net\/website\/wp-content\/uploads\/2023\/03\/1-1.png?fit=1200%2C675&ssl=1&resize=1050%2C600 3x"},"classes":[]}],"jetpack_likes_enabled":true,"jetpack_featured_media_url":"https:\/\/i0.wp.com\/portaileduc.net\/website\/wp-content\/uploads\/2020\/01\/regle-dixit.jpg?fit=408%2C405&ssl=1","_links":{"self":[{"href":"https:\/\/portaileduc.net\/website\/wp-json\/wp\/v2\/posts\/2505","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/portaileduc.net\/website\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/portaileduc.net\/website\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/portaileduc.net\/website\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/portaileduc.net\/website\/wp-json\/wp\/v2\/comments?post=2505"}],"version-history":[{"count":2,"href":"https:\/\/portaileduc.net\/website\/wp-json\/wp\/v2\/posts\/2505\/revisions"}],"predecessor-version":[{"id":5441,"href":"https:\/\/portaileduc.net\/website\/wp-json\/wp\/v2\/posts\/2505\/revisions\/5441"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/portaileduc.net\/website\/wp-json\/wp\/v2\/media\/2506"}],"wp:attachment":[{"href":"https:\/\/portaileduc.net\/website\/wp-json\/wp\/v2\/media?parent=2505"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/portaileduc.net\/website\/wp-json\/wp\/v2\/categories?post=2505"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/portaileduc.net\/website\/wp-json\/wp\/v2\/tags?post=2505"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}